{"id":5299,"date":"2024-05-14T00:59:27","date_gmt":"2024-05-14T00:59:27","guid":{"rendered":"https:\/\/demo06.kory.com.co\/?page_id=5299"},"modified":"2024-05-29T17:09:47","modified_gmt":"2024-05-29T22:09:47","slug":"nuevas-creaciones","status":"publish","type":"page","link":"https:\/\/provimarcas.com\/en\/nuevas-creaciones\/","title":{"rendered":"New Creations"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"5299\" class=\"elementor elementor-5299\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-4c5e9f0e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c5e9f0e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1bc66557\" data-id=\"1bc66557\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3480a463 bdt-icon-type-icon elementor-position-top bdt-icon-effect-none elementor-invisible elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"3480a463\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-star\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"><\/path><\/svg>\n\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h6 class=\"bdt-ep-advanced-icon-box-title\">\n\t\t\t\t<span >\n\t\t\t\t\tOur Services\t\t\t\t<\/span>\n\t\t\t<\/h6>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd329d5 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"fd329d5\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">New Creations<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dfea7a4 elementor-widget elementor-widget-spacer\" data-id=\"7dfea7a4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\r\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7f449670 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f449670\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6e49221b elementor-invisible\" data-id=\"6e49221b\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c0f0dbc bdt-icon-type-image elementor-position-top bdt-icon-effect-none elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"5c0f0dbc\" data-element_type=\"widget\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-1-65x65-2.png\" class=\"attachment-full size-full\" alt=\"Patentes de invenci\u00f3n\" srcset=\"https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-1-65x65-2.png 65w, https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-1-65x65-2-12x12.png 12w\" sizes=\"(max-width: 65px) 100vw, 65px\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h3 class=\"bdt-ep-advanced-icon-box-title\">\n\t\t\t\t<span >\n\t\t\t\t\tPatents\t\t\t\t<\/span>\n\t\t\t<\/h3>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\t<p>A patent is the privilege granted by the state to the inventor as recognition of the investment and efforts made to achieve a technical solution that benefits humanity<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5e18b8 elementor-align-left elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"b5e18b8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/provimarcas.com\/en\/patentes-de-invencion\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">see more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-442ad1f6 elementor-invisible\" data-id=\"442ad1f6\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-174f1c65 bdt-icon-type-image elementor-position-top bdt-icon-effect-none elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"174f1c65\" data-element_type=\"widget\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-2-65x65-2.png\" class=\"attachment-full size-full\" alt=\"Patente de Modelo de utilidad\" srcset=\"https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-2-65x65-2.png 65w, https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-2-65x65-2-12x12.png 12w\" sizes=\"(max-width: 65px) 100vw, 65px\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h3 class=\"bdt-ep-advanced-icon-box-title\">\n\t\t\t\t<span >\n\t\t\t\t\tUtility Models\t\t\t\t<\/span>\n\t\t\t<\/h3>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\t<p>A Utility Model Patent protects any new shape, configuration, or arrangement of elements in a device, tool, etc<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3f0107 elementor-align-left elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"b3f0107\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/provimarcas.com\/en\/patente-de-modelo-de-utilidad\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">see more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-10dc7824 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10dc7824\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c26dd5d elementor-invisible\" data-id=\"c26dd5d\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a7fd160 bdt-icon-type-image elementor-position-top bdt-icon-effect-none elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"2a7fd160\" data-element_type=\"widget\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-3-65x65-2.png\" class=\"attachment-full size-full\" alt=\"Dise\u00f1os industriales\" srcset=\"https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-3-65x65-2.png 65w, https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-3-65x65-2-12x12.png 12w\" sizes=\"(max-width: 65px) 100vw, 65px\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h3 class=\"bdt-ep-advanced-icon-box-title\">\n\t\t\t\t<span >\n\t\t\t\t\tIndustrial Designs\t\t\t\t<\/span>\n\t\t\t<\/h3>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\t<p>An industrial design is the two-dimensional or three-dimensional form of presenting products...<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9830ee4 elementor-align-left elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"9830ee4\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/provimarcas.com\/en\/disenos-industriales\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">see more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-29066aed elementor-invisible\" data-id=\"29066aed\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bc9cda8 bdt-icon-type-image elementor-position-top bdt-icon-effect-none elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"1bc9cda8\" data-element_type=\"widget\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-7-65x65-1.png\" class=\"attachment-full size-full\" alt=\"Esquemas de trazado de circuitos integrados\" srcset=\"https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-7-65x65-1.png 65w, https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-7-65x65-1-12x12.png 12w\" sizes=\"(max-width: 65px) 100vw, 65px\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h3 class=\"bdt-ep-advanced-icon-box-title\">\n\t\t\t\t<span >\n\t\t\t\t\tLayout Designs of Integrated Circuits\t\t\t\t<\/span>\n\t\t\t<\/h3>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\t<p>Integrated circuits are very small electrical circuits that perform electronic operations\u2026<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2e90ea elementor-align-left elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"c2e90ea\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/provimarcas.com\/en\/esquemas-de-trazado-de-circuitos-integrados\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">see more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Nuestro servicio NUEVAS CREACIONES Patentes de invenci\u00f3n Es el privilegio que le otorga el estado al inventor como reconocimiento de la inversi\u00f3n [&hellip;]<\/p>","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NUEVAS CREACIONES - Provimarcas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/provimarcas.com\/en\/nuevas-creaciones\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NUEVAS CREACIONES - Provimarcas\" \/>\n<meta property=\"og:description\" content=\"Nuestro servicio NUEVAS CREACIONES Patentes de invenci\u00f3n Es el privilegio que le otorga el estado al inventor como reconocimiento de la inversi\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/provimarcas.com\/en\/nuevas-creaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Provimarcas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/provimarcas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-29T22:09:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-1-65x65-2.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/provimarcas.com\/nuevas-creaciones\/\",\"url\":\"https:\/\/provimarcas.com\/nuevas-creaciones\/\",\"name\":\"NUEVAS CREACIONES - Provimarcas\",\"isPartOf\":{\"@id\":\"https:\/\/provimarcas.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/provimarcas.com\/nuevas-creaciones\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/provimarcas.com\/nuevas-creaciones\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-1-65x65-2.png\",\"datePublished\":\"2024-05-14T00:59:27+00:00\",\"dateModified\":\"2024-05-29T22:09:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/provimarcas.com\/nuevas-creaciones\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/provimarcas.com\/nuevas-creaciones\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/provimarcas.com\/nuevas-creaciones\/#primaryimage\",\"url\":\"https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-1-65x65-2.png\",\"contentUrl\":\"https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-1-65x65-2.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/provimarcas.com\/nuevas-creaciones\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/provimarcas.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NUEVAS CREACIONES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/provimarcas.com\/#website\",\"url\":\"https:\/\/provimarcas.com\/\",\"name\":\"Provimarcas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/provimarcas.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/provimarcas.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/provimarcas.com\/#organization\",\"name\":\"Provimarcas\",\"url\":\"https:\/\/provimarcas.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/provimarcas.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/provimarcas.com\/wp-content\/uploads\/2022\/09\/ingles_mobile-provimarcas.jpg\",\"contentUrl\":\"https:\/\/provimarcas.com\/wp-content\/uploads\/2022\/09\/ingles_mobile-provimarcas.jpg\",\"width\":480,\"height\":420,\"caption\":\"Provimarcas\"},\"image\":{\"@id\":\"https:\/\/provimarcas.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/provimarcas\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NUEVAS CREACIONES - Provimarcas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/provimarcas.com\/en\/nuevas-creaciones\/","og_locale":"en_US","og_type":"article","og_title":"NUEVAS CREACIONES - Provimarcas","og_description":"Nuestro servicio NUEVAS CREACIONES Patentes de invenci\u00f3n Es el privilegio que le otorga el estado al inventor como reconocimiento de la inversi\u00f3n [&hellip;]","og_url":"https:\/\/provimarcas.com\/en\/nuevas-creaciones\/","og_site_name":"Provimarcas","article_publisher":"https:\/\/www.facebook.com\/provimarcas","article_modified_time":"2024-05-29T22:09:47+00:00","og_image":[{"url":"https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-1-65x65-2.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/provimarcas.com\/nuevas-creaciones\/","url":"https:\/\/provimarcas.com\/nuevas-creaciones\/","name":"NUEVAS CREACIONES - Provimarcas","isPartOf":{"@id":"https:\/\/provimarcas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/provimarcas.com\/nuevas-creaciones\/#primaryimage"},"image":{"@id":"https:\/\/provimarcas.com\/nuevas-creaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-1-65x65-2.png","datePublished":"2024-05-14T00:59:27+00:00","dateModified":"2024-05-29T22:09:47+00:00","breadcrumb":{"@id":"https:\/\/provimarcas.com\/nuevas-creaciones\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/provimarcas.com\/nuevas-creaciones\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/provimarcas.com\/nuevas-creaciones\/#primaryimage","url":"https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-1-65x65-2.png","contentUrl":"https:\/\/provimarcas.com\/wp-content\/uploads\/2024\/05\/Recurso-1-65x65-2.png"},{"@type":"BreadcrumbList","@id":"https:\/\/provimarcas.com\/nuevas-creaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/provimarcas.com\/"},{"@type":"ListItem","position":2,"name":"NUEVAS CREACIONES"}]},{"@type":"WebSite","@id":"https:\/\/provimarcas.com\/#website","url":"https:\/\/provimarcas.com\/","name":"Provimarcas","description":"","publisher":{"@id":"https:\/\/provimarcas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/provimarcas.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/provimarcas.com\/#organization","name":"Provimarcas","url":"https:\/\/provimarcas.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/provimarcas.com\/#\/schema\/logo\/image\/","url":"https:\/\/provimarcas.com\/wp-content\/uploads\/2022\/09\/ingles_mobile-provimarcas.jpg","contentUrl":"https:\/\/provimarcas.com\/wp-content\/uploads\/2022\/09\/ingles_mobile-provimarcas.jpg","width":480,"height":420,"caption":"Provimarcas"},"image":{"@id":"https:\/\/provimarcas.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/provimarcas"]}]}},"_links":{"self":[{"href":"https:\/\/provimarcas.com\/en\/wp-json\/wp\/v2\/pages\/5299"}],"collection":[{"href":"https:\/\/provimarcas.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/provimarcas.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/provimarcas.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/provimarcas.com\/en\/wp-json\/wp\/v2\/comments?post=5299"}],"version-history":[{"count":9,"href":"https:\/\/provimarcas.com\/en\/wp-json\/wp\/v2\/pages\/5299\/revisions"}],"predecessor-version":[{"id":8575,"href":"https:\/\/provimarcas.com\/en\/wp-json\/wp\/v2\/pages\/5299\/revisions\/8575"}],"wp:attachment":[{"href":"https:\/\/provimarcas.com\/en\/wp-json\/wp\/v2\/media?parent=5299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}